{"id":558,"date":"2026-03-24T06:31:01","date_gmt":"2026-03-24T06:31:01","guid":{"rendered":"https:\/\/fiets.2move-2wheel.com\/home\/"},"modified":"2026-06-04T07:29:46","modified_gmt":"2026-06-04T07:29:46","slug":"accueil","status":"publish","type":"page","link":"https:\/\/fiets.2move-2wheel.com\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_direction=\u00a0\u00bb90deg\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bb#ec9f2a 40%|rgba(255,255,255,0) 40%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/04\/2move-2wheel-fietsbanden-groothandel.jpg\u00a0\u00bb background_size=\u00a0\u00bbcontain\u00a0\u00bb background_position=\u00a0\u00bbbottom_right\u00a0\u00bb custom_padding=\u00a0\u00bb3%||3%||true|false\u00a0\u00bb background_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb use_background_color_gradient_phone=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops_phone=\u00a0\u00bbrgba(236,159,42,0.85) 100%|rgba(255,255,255,0) 100%\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb2_5,3_5&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb84%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb header_font=\u00a0\u00bb|||on|||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb36px\u00a0\u00bb header_2_font=\u00a0\u00bb|||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb52px\u00a0\u00bb header_3_font=\u00a0\u00bb|||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb width_tablet=\u00a0\u00bb90%\u00a0\u00bb width_phone=\u00a0\u00bb100%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||||false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb36px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb32px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb28px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb text_orientation_tablet=\u00a0\u00bb\u00a0\u00bb text_orientation_phone=\u00a0\u00bbcenter\u00a0\u00bb text_orientation_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>2Move 2Wheel<\/h1>\n<h2>Le partenaire en pneus de v\u00e9lo<\/h2>\n<p>2Move 2Wheel est le distributeur exclusif des pneus de v\u00e9lo Continental dans le Benelux. \u00c0 partir de notre stock, nous soutenons les grossistes, les sp\u00e9cialistes du v\u00e9lo et les fabricants avec une gamme compl\u00e8te, une livraison rapide et un accompagnement personnalis\u00e9.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_5&Prime; disabled_on=\u00a0\u00bbon|on|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#efefef\u00a0\u00bb custom_padding=\u00a0\u00bb0%||0%||true|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb border_width_top=\u00a0\u00bb3px\u00a0\u00bb border_color_top=\u00a0\u00bb#FFFFFF\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb width_tablet=\u00a0\u00bb100%\u00a0\u00bb width_phone=\u00a0\u00bb80%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb max_width_tablet=\u00a0\u00bb2560px\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb6%||4%||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb2%|4%|1%|4%|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb2%|4%|1%|4%|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0%|0%|2%|0%|false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_width_right=\u00a0\u00bb3px\u00a0\u00bb border_color_right=\u00a0\u00bb#FFFFFF\u00a0\u00bb border_color_bottom=\u00a0\u00bb#FFFFFF\u00a0\u00bb border_width_right_tablet=\u00a0\u00bb3px\u00a0\u00bb border_width_right_phone=\u00a0\u00bb0px\u00a0\u00bb border_width_right_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_width_bottom_phone=\u00a0\u00bb0px\u00a0\u00bb border_width_bottom_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bb\u00c0 propos de 2Move 2Wheel\u00a0\u00bb content_max_width=\u00a0\u00bb100%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh2&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb\u00a0\u00bb body_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb body_line_height_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb text_orientation_tablet=\u00a0\u00bb\u00a0\u00bb text_orientation_phone=\u00a0\u00bbcenter\u00a0\u00bb text_orientation_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Distributeur de pneus de v\u00e9lo Continental dans le Benelux.[\/et_pb_blurb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/a-propos-de-nous\/\u00a0\u00bb button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbleft\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#ec9f2a\u00a0\u00bb button_bg_color=\u00a0\u00bb#efefef\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_radius=\u00a0\u00bb4px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x24;||divi||400&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb2%|4%|1%|4%|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb2%|4%|1%|4%|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb6%|0%|2%|0%|false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_width_top=\u00a0\u00bb0px\u00a0\u00bb border_color_top=\u00a0\u00bb#FFFFFF\u00a0\u00bb border_width_right=\u00a0\u00bb3px\u00a0\u00bb border_color_right=\u00a0\u00bb#FFFFFF\u00a0\u00bb border_width_bottom=\u00a0\u00bb0px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#FFFFFF\u00a0\u00bb border_color_left=\u00a0\u00bb#FFFFFF\u00a0\u00bb border_width_top_tablet=\u00a0\u00bb0px\u00a0\u00bb border_width_top_phone=\u00a0\u00bb2px\u00a0\u00bb border_width_top_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_width_right_tablet=\u00a0\u00bb3px\u00a0\u00bb border_width_right_phone=\u00a0\u00bb0px\u00a0\u00bb border_width_right_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_width_bottom_tablet=\u00a0\u00bb0px\u00a0\u00bb border_width_bottom_phone=\u00a0\u00bb2px\u00a0\u00bb border_width_bottom_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbDevenez partenaire anti-crevaison\u00a0\u00bb content_max_width=\u00a0\u00bb100%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh2&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb\u00a0\u00bb body_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb body_line_height_phone=\u00a0\u00bb1.8em\u00a0\u00bb body_line_height_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb text_orientation_tablet=\u00a0\u00bb\u00a0\u00bb text_orientation_phone=\u00a0\u00bbcenter\u00a0\u00bb text_orientation_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Programme de garantie sur les pneus de v\u00e9lo Continental.[\/et_pb_blurb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/garantie-anti-crevaison\/\u00a0\u00bb button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbleft\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#ec9f2a\u00a0\u00bb button_bg_color=\u00a0\u00bb#efefef\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_radius=\u00a0\u00bb4px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x24;||divi||400&Prime; custom_padding=\u00a0\u00bb|||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb2%|4%|1%|4%|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb2%|4%|1%|4%|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb6%|0%|0%|0%|false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbD\u00e9couvrez notre assortiment\u00a0\u00bb content_max_width=\u00a0\u00bb100%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh2&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb\u00a0\u00bb body_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb text_orientation_tablet=\u00a0\u00bb\u00a0\u00bb text_orientation_phone=\u00a0\u00bbcenter\u00a0\u00bb text_orientation_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Pneus de v\u00e9lo Continental pour chaque type de v\u00e9lo.[\/et_pb_blurb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/assortiment\/\u00a0\u00bb button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbleft\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#ec9f2a\u00a0\u00bb button_bg_color=\u00a0\u00bb#efefef\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_radius=\u00a0\u00bb4px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x24;||divi||400&Prime; custom_padding=\u00a0\u00bb|||0px|false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_duration=\u00a0\u00bb1200ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||10%||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin: auto;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb22px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Tout pour le meilleur pneu<\/h2>\n<p>2Move 2Wheel est le distributeur exclusif des pneus de v\u00e9lo Continental dans le Benelux. \u00c0 partir de notre stock, nous soutenons les grossistes, les sp\u00e9cialistes du v\u00e9lo et les fabricants avec une gamme compl\u00e8te et une disponibilit\u00e9 constante. Gr\u00e2ce \u00e0 notre connaissance du march\u00e9 et \u00e0 un contact personnalis\u00e9, nous aidons les revendeurs \u00e0 faire le bon choix de pneus.[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb#Video\u00a0\u00bb button_text=\u00a0\u00bbRegardez notre vid\u00e9o d\u2019entreprise\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#072f49&Prime; button_border_color=\u00a0\u00bb#072f49&Prime; button_border_radius=\u00a0\u00bb4px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb12px|4%|12px|4%|true|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_direction=\u00a0\u00bbright\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/04\/fietsbanden-groothandel-2move-2wheel.jpg\u00a0\u00bb alt=\u00a0\u00bb2Move 2Wheel\u00a0\u00bb title_text=\u00a0\u00bb2Move 2Wheel\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_duration=\u00a0\u00bb1200ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/04\/lekker-niet-lek-zekerheid.jpg\u00a0\u00bb alt=\u00a0\u00bbGarantie Lekker niet Lek\u00a0\u00bb title_text=\u00a0\u00bbGarantie Lekker niet Lek\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_direction=\u00a0\u00bbright\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin: auto;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; header_2_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb22px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb1.2em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2>Profitez de la garantie anti-crevaison<\/h2>\n<p>Avec la garantie anti-crevaison, vous offrez \u00e0 vos clients une s\u00e9curit\u00e9 suppl\u00e9mentaire lors de l\u2019achat de pneus de v\u00e9lo Continental s\u00e9lectionn\u00e9s. Si un client cr\u00e8ve dans l\u2019ann\u00e9e, la r\u00e9paration est rembours\u00e9e via 2Move 2Wheel. Vous offrez ainsi \u00e0 vos clients une tranquillit\u00e9 d\u2019esprit suppl\u00e9mentaire lors de l\u2019achat de pneus premium.[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/garantie-anti-crevaison\/\u00a0\u00bb button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#072f49&Prime; button_border_color=\u00a0\u00bb#072f49&Prime; button_border_radius=\u00a0\u00bb4px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb12px|4%|12px|4%|true|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb admin_label=\u00a0\u00bbAccordion Image Demo 03&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; background_color=\u00a0\u00bb#ec9f2a\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb background_blend=\u00a0\u00bboverlay\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb60px||60px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb60px||60px||false|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,2_3&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; background_enable_color=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb width_tablet=\u00a0\u00bb90%\u00a0\u00bb width_phone=\u00a0\u00bb100%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb8%||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; custom_padding=\u00a0\u00bb|2%||4%|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|2%||4%|false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|10%|6%|10%|false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin: auto;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb header_2_font_size=\u00a0\u00bb28px\u00a0\u00bb header_3_font=\u00a0\u00bb|||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb width_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||||false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb28px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb22px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>D\u00e9couvrez notre assortiment<\/h2>\n<p>L\u2019assortiment de 2Move 2Wheel se compose de pneus de v\u00e9lo Continental pour diff\u00e9rents types de v\u00e9los et d\u2019utilisations. Des pneus pour un usage quotidien aux pneus con\u00e7us pour la vitesse, la polyvalence et une adh\u00e9rence maximale.[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/assortiment\/\u00a0\u00bb button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#072f49&Prime; button_border_color=\u00a0\u00bb#072f49&Prime; button_border_radius=\u00a0\u00bb4px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb12px|4%|12px|4%|true|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_border_color__hover=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_text_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][dipi_image_accordion accordion_height=\u00a0\u00bb520px\u00a0\u00bb active_image_relative_width=\u00a0\u00bb8&Prime; accordion_direction_tablet=\u00a0\u00bb\u00a0\u00bb accordion_direction_phone=\u00a0\u00bbvertical\u00a0\u00bb accordion_direction_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][dipi_image_accordion_child title=\u00a0\u00bbVille \/ VTC\u00a0\u00bb bg_img=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/04\/city-fietsbanden.jpg\u00a0\u00bb use_onload_active=\u00a0\u00bboff\u00a0\u00bb alt=\u00a0\u00bbPneus ville et VTC\u00a0\u00bb accordion_title=\u00a0\u00bbVille \/ VTC\u00a0\u00bb accordion_description=\u00a0\u00bb<\/p>\n<p>Pour un usage quotidien, des trajets domicile-travail aux sorties plus longues.<\/p>\n<p>\u00a0\u00bb show_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb accordion_button_link=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/ville-vtc\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb accordion_title_level=\u00a0\u00bbh3&Prime; accordion_title_font=\u00a0\u00bb|||on|||||\u00a0\u00bb accordion_title_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_title_font_size=\u00a0\u00bb26px\u00a0\u00bb accordion_title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_desc_font=\u00a0\u00bb|600|||||||\u00a0\u00bb accordion_desc_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_desc_font_size=\u00a0\u00bb18px\u00a0\u00bb accordion_desc_line_height=\u00a0\u00bb1.8em\u00a0\u00bb custom_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_size=\u00a0\u00bb20px\u00a0\u00bb accordion_button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb accordion_button_border_width=\u00a0\u00bb2px\u00a0\u00bb accordion_button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_border_radius=\u00a0\u00bb4px\u00a0\u00bb accordion_button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb accordion_button_use_icon=\u00a0\u00bboff\u00a0\u00bb accordion_button_custom_padding=\u00a0\u00bb12px||12px||true|false\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|2%||2%|false|true\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/ville-vtc\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb image_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb image_bg_color__hover=\u00a0\u00bbrgba(7,47,73,0.6)\u00a0\u00bb image_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_border_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_text_color__hover=\u00a0\u00bb#FFFFFF\u00a0\u00bb][\/dipi_image_accordion_child][dipi_image_accordion_child title=\u00a0\u00bbRoute\u00a0\u00bb bg_img=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/04\/racefiets-banden.jpg\u00a0\u00bb use_onload_active=\u00a0\u00bboff\u00a0\u00bb alt=\u00a0\u00bbPneus de route\u00a0\u00bb accordion_title=\u00a0\u00bbRoute\u00a0\u00bb accordion_description=\u00a0\u00bb<\/p>\n<p>Pour la vitesse, le contr\u00f4le et une conduite fluide sur route.<\/p>\n<p>\u00a0\u00bb show_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb accordion_button_link=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/route\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb accordion_title_level=\u00a0\u00bbh3&Prime; accordion_title_font=\u00a0\u00bb|||on|||||\u00a0\u00bb accordion_title_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_title_font_size=\u00a0\u00bb26px\u00a0\u00bb accordion_title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_desc_font=\u00a0\u00bb|600|||||||\u00a0\u00bb accordion_desc_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_desc_font_size=\u00a0\u00bb18px\u00a0\u00bb accordion_desc_line_height=\u00a0\u00bb1.8em\u00a0\u00bb custom_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_size=\u00a0\u00bb20px\u00a0\u00bb accordion_button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb accordion_button_border_width=\u00a0\u00bb2px\u00a0\u00bb accordion_button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_border_radius=\u00a0\u00bb4px\u00a0\u00bb accordion_button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb accordion_button_use_icon=\u00a0\u00bboff\u00a0\u00bb accordion_button_custom_padding=\u00a0\u00bb12px||12px||true|false\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|2%||2%|false|true\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/route\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb image_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb image_bg_color__hover=\u00a0\u00bbrgba(7,47,73,0.6)\u00a0\u00bb image_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_border_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_text_color__hover=\u00a0\u00bb#FFFFFF\u00a0\u00bb][\/dipi_image_accordion_child][dipi_image_accordion_child title=\u00a0\u00bbGravel\u00a0\u00bb bg_img=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/04\/gravelbanden.jpg\u00a0\u00bb use_onload_active=\u00a0\u00bboff\u00a0\u00bb alt=\u00a0\u00bbPneus gravel\u00a0\u00bb accordion_title=\u00a0\u00bbGravel\u00a0\u00bb accordion_description=\u00a0\u00bb<\/p>\n<p>Pour l\u2019adh\u00e9rence et le confort sur des surfaces vari\u00e9es.<\/p>\n<p>\u00a0\u00bb show_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb accordion_button_link=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/gravel\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb accordion_title_level=\u00a0\u00bbh3&Prime; accordion_title_font=\u00a0\u00bb|||on|||||\u00a0\u00bb accordion_title_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_title_font_size=\u00a0\u00bb26px\u00a0\u00bb accordion_title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_desc_font=\u00a0\u00bb|600|||||||\u00a0\u00bb accordion_desc_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_desc_font_size=\u00a0\u00bb18px\u00a0\u00bb accordion_desc_line_height=\u00a0\u00bb1.8em\u00a0\u00bb custom_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_size=\u00a0\u00bb20px\u00a0\u00bb accordion_button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb accordion_button_border_width=\u00a0\u00bb2px\u00a0\u00bb accordion_button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_border_radius=\u00a0\u00bb4px\u00a0\u00bb accordion_button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb accordion_button_use_icon=\u00a0\u00bboff\u00a0\u00bb accordion_button_custom_padding=\u00a0\u00bb12px||12px||true|false\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|2%||2%|false|true\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/gravel\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb image_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb image_bg_color__hover=\u00a0\u00bbrgba(7,47,73,0.6)\u00a0\u00bb image_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_border_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_text_color__hover=\u00a0\u00bb#FFFFFF\u00a0\u00bb][\/dipi_image_accordion_child][dipi_image_accordion_child title=\u00a0\u00bbVTT\u00a0\u00bb bg_img=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/04\/mtb-banden.jpg\u00a0\u00bb use_onload_active=\u00a0\u00bboff\u00a0\u00bb alt=\u00a0\u00bbPneus VTT\u00a0\u00bb accordion_title=\u00a0\u00bbVTT\u00a0\u00bb accordion_description=\u00a0\u00bbPour une adh\u00e9rence et un contr\u00f4le maximaux en tout-terrain.\u00a0\u00bb show_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb accordion_button_link=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/vtt\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb accordion_title_level=\u00a0\u00bbh3&Prime; accordion_title_font=\u00a0\u00bb|||on|||||\u00a0\u00bb accordion_title_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_title_font_size=\u00a0\u00bb26px\u00a0\u00bb accordion_title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_desc_font=\u00a0\u00bb|600|||||||\u00a0\u00bb accordion_desc_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_desc_font_size=\u00a0\u00bb18px\u00a0\u00bb accordion_desc_line_height=\u00a0\u00bb1.8em\u00a0\u00bb custom_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_size=\u00a0\u00bb20px\u00a0\u00bb accordion_button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb accordion_button_border_width=\u00a0\u00bb2px\u00a0\u00bb accordion_button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_border_radius=\u00a0\u00bb4px\u00a0\u00bb accordion_button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb accordion_button_use_icon=\u00a0\u00bboff\u00a0\u00bb accordion_button_custom_padding=\u00a0\u00bb12px||12px||true|false\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|2%||2%|false|true\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/vtt\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb image_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb image_bg_color__hover=\u00a0\u00bbrgba(7,47,73,0.6)\u00a0\u00bb image_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_border_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_text_color__hover=\u00a0\u00bb#FFFFFF\u00a0\u00bb][\/dipi_image_accordion_child][dipi_image_accordion_child title=\u00a0\u00bbDescente\u00a0\u00bb bg_img=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/04\/downhill-banden.jpg\u00a0\u00bb use_onload_active=\u00a0\u00bboff\u00a0\u00bb alt=\u00a0\u00bbPneus de descente\u00a0\u00bb accordion_title=\u00a0\u00bbDescente\u00a0\u00bb accordion_description=\u00a0\u00bbPour une adh\u00e9rence et un contr\u00f4le maximaux lors des descentes.\u00a0\u00bb show_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text=\u00a0\u00bbPlus d\u2019informations\u00a0\u00bb accordion_button_link=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/descente\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb accordion_title_level=\u00a0\u00bbh3&Prime; accordion_title_font=\u00a0\u00bb|||on|||||\u00a0\u00bb accordion_title_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_title_font_size=\u00a0\u00bb26px\u00a0\u00bb accordion_title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_desc_font=\u00a0\u00bb|600|||||||\u00a0\u00bb accordion_desc_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_desc_font_size=\u00a0\u00bb18px\u00a0\u00bb accordion_desc_line_height=\u00a0\u00bb1.8em\u00a0\u00bb custom_accordion_button=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_size=\u00a0\u00bb20px\u00a0\u00bb accordion_button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb accordion_button_border_width=\u00a0\u00bb2px\u00a0\u00bb accordion_button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb accordion_button_border_radius=\u00a0\u00bb4px\u00a0\u00bb accordion_button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb accordion_button_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb accordion_button_use_icon=\u00a0\u00bboff\u00a0\u00bb accordion_button_custom_padding=\u00a0\u00bb12px||12px||true|false\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|2%||2%|false|true\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/fr\/descente\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb image_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb image_bg_color__hover=\u00a0\u00bbrgba(7,47,73,0.6)\u00a0\u00bb image_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_bg_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb accordion_button_border_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb accordion_button_border_color__hover=\u00a0\u00bb#ec9f2a\u00a0\u00bb accordion_button_text_color__hover=\u00a0\u00bb#FFFFFF\u00a0\u00bb][\/dipi_image_accordion_child][\/dipi_image_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#072f49&Prime; custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb1280px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbDistributeur exclusif dans le Benelux\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xf14a;||fa||900&Prime; icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb22px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh2&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb22px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb\u00a0\u00bb body_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]2Move 2Wheel est le distributeur exclusif des pneus de v\u00e9lo Continental dans le Benelux. Dans ce r\u00f4le, nous assurons la distribution aupr\u00e8s des fabricants, des grossistes et des revendeurs.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbSupport commercial\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xf14a;||fa||900&Prime; icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb22px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh2&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb22px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb\u00a0\u00bb body_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]2Move 2Wheel accompagne les revendeurs dans la vente de pneus de v\u00e9lo Continental. Gr\u00e2ce \u00e0 des supports de pr\u00e9sentation et du mat\u00e9riel PLV, l\u2019assortiment est clairement mis en valeur en magasin.[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb1280px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbLivraison rapide\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xf14a;||fa||900&Prime; icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb22px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh2&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb22px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb\u00a0\u00bb body_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Gr\u00e2ce \u00e0 son propre entrep\u00f4t et \u00e0 des circuits courts avec l\u2019usine, 2Move 2Wheel assure une livraison rapide et une large disponibilit\u00e9 de l\u2019assortiment.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbLarge assortiment\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xf14a;||fa||900&Prime; icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb22px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh2&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb22px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb\u00a0\u00bb body_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]L\u2019assortiment de 2Move 2Wheel comprend une large s\u00e9lection de pneus de v\u00e9lo Continental. Ainsi, un pneu adapt\u00e9 peut \u00eatre propos\u00e9 pour chaque type de v\u00e9lo.[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#efefef\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||6%||false|false\u00a0\u00bb bottom_divider_style=\u00a0\u00bbslant\u00a0\u00bb bottom_divider_color=\u00a0\u00bb#ec9f2a\u00a0\u00bb bottom_divider_height=\u00a0\u00bb38px\u00a0\u00bb bottom_divider_flip=\u00a0\u00bbhorizontal\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_4,1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb22px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Contact et conseil personnalis\u00e9s<\/h2>\n<p>Nos sp\u00e9cialistes exp\u00e9riment\u00e9s sont \u00e0 votre disposition lorsque n\u00e9cessaire. Ils connaissent votre entreprise, ce qui leur permet de r\u00e9agir rapidement et de vous fournir des conseils personnalis\u00e9s. Toujours avec le m\u00eame objectif : <span style=\"text-decoration: underline;\"><strong>tout pour le meilleur pneu<\/strong><\/span>.[\/et_pb_text][et_pb_blurb title=\u00a0\u00bbT\u00e9l\u00e9phone\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe090;||divi||400&Prime; icon_color=\u00a0\u00bb#072f49&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb20px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbleft\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb body_line_height=\u00a0\u00bb1em\u00a0\u00bb body_link_text_color=\u00a0\u00bb#072f49&Prime; animation=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><a href=\"tel:0881658090\">+31 (0)88 165 80 90<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00a0\u00bbE-mail\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xf0e0;||fa||900&Prime; icon_color=\u00a0\u00bb#072f49&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb20px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbleft\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb body_line_height=\u00a0\u00bb1em\u00a0\u00bb body_link_text_color=\u00a0\u00bb#072f49&Prime; animation=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><a href=\"mailto:2wheel@2-move.com\">2wheel@2-move.com<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbLuuk van Harn\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/03\/luuk-van-harn-2move-2wheel.jpg\u00a0\u00bb alt=\u00a0\u00bbLuuk van Harn\u00a0\u00bb image_icon_width=\u00a0\u00bb72%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb border_radii_image=\u00a0\u00bbon|120px|120px|120px|120px\u00a0\u00bb border_width_all_image=\u00a0\u00bb2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00a0\u00bbMilo Hoogeveen\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/03\/milo-hoogeveen-2move-2wheel.jpg\u00a0\u00bb alt=\u00a0\u00bbMilo Hoogeveen\u00a0\u00bb image_icon_width=\u00a0\u00bb72%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb border_radii_image=\u00a0\u00bbon|120px|120px|120px|120px\u00a0\u00bb border_width_all_image=\u00a0\u00bb2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbPatrick Keijmel\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/03\/patrick-keijmel-2move-2wheel.jpg\u00a0\u00bb alt=\u00a0\u00bbPatrick Keijmel\u00a0\u00bb image_icon_width=\u00a0\u00bb72%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb border_radii_image=\u00a0\u00bbon|120px|120px|120px|120px\u00a0\u00bb border_width_all_image=\u00a0\u00bb2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00a0\u00bbGerold Boersen\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/fiets.2move-2wheel.com\/wp-content\/uploads\/2026\/04\/gerold-boersen-2move-2wheel.jpg\u00a0\u00bb alt=\u00a0\u00bbGerold Boersen\u00a0\u00bb image_icon_width=\u00a0\u00bb72%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font=\u00a0\u00bbProxima Nova Black||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb border_radii_image=\u00a0\u00bbon|120px|120px|120px|120px\u00a0\u00bb border_width_all_image=\u00a0\u00bb2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbPopup &#8211; #Video\u00a0\u00bb module_id=\u00a0\u00bbVideo\u00a0\u00bb module_class=\u00a0\u00bbpopup\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb60%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb da_is_popup=\u00a0\u00bbon\u00a0\u00bb da_popup_slug=\u00a0\u00bbVideo\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=FUPUSYLQ_ng\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2Move 2Wheel Le partenaire en pneus de v\u00e9lo 2Move 2Wheel est le distributeur exclusif des pneus de v\u00e9lo Continental dans le Benelux. \u00c0 partir de notre stock, nous soutenons les grossistes, les sp\u00e9cialistes du v\u00e9lo et les fabricants avec une gamme compl\u00e8te, une livraison rapide et un accompagnement personnalis\u00e9.Distributeur de pneus de v\u00e9lo Continental dans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"dipi_cpt_category":[],"class_list":["post-558","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2Move 2Wheel | Le partenaire en pneus de v\u00e9lo<\/title>\n<meta name=\"description\" content=\"2Move 2Wheel est distributeur exclusif de pneus Continental dans le Benelux. Nous aidons les revendeurs \u00e0 choisir le bon pneu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fiets.2move-2wheel.com\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2Move 2Wheel | Le partenaire en pneus de v\u00e9lo\" \/>\n<meta property=\"og:description\" content=\"2Move 2Wheel est distributeur exclusif de pneus Continental dans le Benelux. Nous aidons les revendeurs \u00e0 choisir le bon pneu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fiets.2move-2wheel.com\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"2Move 2Wheel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T07:29:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/\",\"url\":\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/\",\"name\":\"2Move 2Wheel | Le partenaire en pneus de v\u00e9lo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-03-24T06:31:01+00:00\",\"dateModified\":\"2026-06-04T07:29:46+00:00\",\"description\":\"2Move 2Wheel est distributeur exclusif de pneus Continental dans le Benelux. Nous aidons les revendeurs \u00e0 choisir le bon pneu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/\",\"name\":\"2Move 2Wheel\",\"description\":\"Alles voor de beste band\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fiets.2move-2wheel.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2Move 2Wheel | Le partenaire en pneus de v\u00e9lo","description":"2Move 2Wheel est distributeur exclusif de pneus Continental dans le Benelux. Nous aidons les revendeurs \u00e0 choisir le bon pneu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fiets.2move-2wheel.com\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"2Move 2Wheel | Le partenaire en pneus de v\u00e9lo","og_description":"2Move 2Wheel est distributeur exclusif de pneus Continental dans le Benelux. Nous aidons les revendeurs \u00e0 choisir le bon pneu.","og_url":"https:\/\/fiets.2move-2wheel.com\/fr\/","og_site_name":"2Move 2Wheel","article_modified_time":"2026-06-04T07:29:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fiets.2move-2wheel.com\/fr\/","url":"https:\/\/fiets.2move-2wheel.com\/fr\/","name":"2Move 2Wheel | Le partenaire en pneus de v\u00e9lo","isPartOf":{"@id":"https:\/\/fiets.2move-2wheel.com\/fr\/#website"},"datePublished":"2026-03-24T06:31:01+00:00","dateModified":"2026-06-04T07:29:46+00:00","description":"2Move 2Wheel est distributeur exclusif de pneus Continental dans le Benelux. Nous aidons les revendeurs \u00e0 choisir le bon pneu.","breadcrumb":{"@id":"https:\/\/fiets.2move-2wheel.com\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fiets.2move-2wheel.com\/fr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fiets.2move-2wheel.com\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fiets.2move-2wheel.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/fiets.2move-2wheel.com\/fr\/#website","url":"https:\/\/fiets.2move-2wheel.com\/fr\/","name":"2Move 2Wheel","description":"Alles voor de beste band","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fiets.2move-2wheel.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/fiets.2move-2wheel.com\/fr\/wp-json\/wp\/v2\/pages\/558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiets.2move-2wheel.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fiets.2move-2wheel.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fiets.2move-2wheel.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fiets.2move-2wheel.com\/fr\/wp-json\/wp\/v2\/comments?post=558"}],"version-history":[{"count":15,"href":"https:\/\/fiets.2move-2wheel.com\/fr\/wp-json\/wp\/v2\/pages\/558\/revisions"}],"predecessor-version":[{"id":1021,"href":"https:\/\/fiets.2move-2wheel.com\/fr\/wp-json\/wp\/v2\/pages\/558\/revisions\/1021"}],"wp:attachment":[{"href":"https:\/\/fiets.2move-2wheel.com\/fr\/wp-json\/wp\/v2\/media?parent=558"}],"wp:term":[{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/fiets.2move-2wheel.com\/fr\/wp-json\/wp\/v2\/dipi_cpt_category?post=558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}